{"id":9040,"date":"2026-05-12T13:39:47","date_gmt":"2026-05-12T13:39:47","guid":{"rendered":"https:\/\/ssb-hagen.de\/?p=9040"},"modified":"2026-05-12T13:39:52","modified_gmt":"2026-05-12T13:39:52","slug":"bewegung-spiel-und-spass-bei-der-kids-avenue","status":"publish","type":"post","link":"https:\/\/ssb-hagen.de\/index.php\/2026\/05\/12\/bewegung-spiel-und-spass-bei-der-kids-avenue\/","title":{"rendered":"Bewegung, Spiel und Spa\u00df bei der Kids Avenue"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"9040\" class=\"elementor elementor-9040\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3d17d86b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3d17d86b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-362f2b72\" data-id=\"362f2b72\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cfdfe2f elementor-widget elementor-widget-spacer\" data-id=\"cfdfe2f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-20713b12 elementor-widget elementor-widget-text-editor\" data-id=\"20713b12\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\n<p>Im Rahmen der Veranstaltung Hagen bl\u00fcht auf war der Stadtsportbund Hagen am Sonntag Teil der Kids Avenue in der Hagener Innenstadt. Auf der Kinder-Erlebnis-Meile konnten zahlreiche Kinder das Kinderbewegungsabzeichen \u201eKibaz\u201c ausprobieren und dabei mit viel Freude verschiedene Bewegungsstationen absolvieren.<\/p>\n\n\n\n<p>Das Kibaz ist ein Bewegungsparcours der Sportjugend NRW f\u00fcr Kinder im Vorschulalter. An insgesamt zehn Stationen stehen nicht Leistung oder Wettbewerb im Vordergrund, sondern Spa\u00df an Bewegung, gemeinsames Ausprobieren und das Sammeln neuer Erfahrungen. Die Kinder konnten unter anderem balancieren, werfen, koordinative Aufgaben l\u00f6sen oder ihre Sinne bei einem F\u00fchlmemory testen.<br>Einige unserer Stationen waren beispielsweise Slackline-Balancieren, Balltransport, Koordinationsleiter, Fluss\u00fcberquerung, Stelzenlaufen oder Zielwerfen.<\/p>\n\n\n\n<p>Besonders erfreulich war das gro\u00dfe Interesse der Kinder und Familien, die mit viel Begeisterung an den Stationen aktiv wurden. \u00dcber den gesamten Nachmittag herrschte eine tolle Atmosph\u00e4re voller Bewegung, Motivation und guter Laune.<\/p>\n\n\n\n<p>Ein besonderer Dank gilt unseren engagierten Helferinnen und Helfern. Unterst\u00fctzt wurde die Aktion von zahlreichen <a href=\"https:\/\/www.sportjugend.nrw\/unsere-themen\/sporthelfer-programm\">Sporthelferinnen und Sporthelfern<\/a> verschiedener Hagener Schulen, die die Stationen betreuten, Kinder motivierten und f\u00fcr einen reibungslosen Ablauf sorgten. Ohne ihren Einsatz w\u00e4re eine solche Aktion nicht m\u00f6glich gewesen. Ihr Engagement hat ma\u00dfgeblich dazu beigetragen, den Kindern einen abwechslungsreichen und bewegungsreichen Tag zu erm\u00f6glichen.<\/p>\n\n\n\n<p>Wir freuen uns sehr, Teil von Hagen bl\u00fcht auf gewesen zu sein und gemeinsam mit vielen Partnern Bewegung und Sport in die Hagener Innenstadt gebracht zu haben.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e0a2214 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e0a2214\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-eaa3209\" data-id=\"eaa3209\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b882a98 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"b882a98\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Bild Karussell\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 von 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ssb-hagen.de\/wp-content\/uploads\/2026\/05\/IMG_20260510_131301-1-150x150.jpg\" alt=\"IMG_20260510_131301\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 von 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ssb-hagen.de\/wp-content\/uploads\/2026\/05\/IMG_20260510_142120-150x150.jpg\" alt=\"IMG_20260510_142120\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 von 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ssb-hagen.de\/wp-content\/uploads\/2026\/05\/IMG_20260510_143911-150x150.jpg\" alt=\"IMG_20260510_143911\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 von 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ssb-hagen.de\/wp-content\/uploads\/2026\/05\/IMG_20260510_143949-150x150.jpg\" alt=\"IMG_20260510_143949\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 von 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ssb-hagen.de\/wp-content\/uploads\/2026\/05\/IMG_20260510_150044-150x150.jpg\" alt=\"IMG_20260510_150044\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Im Rahmen der Veranstaltung Hagen bl\u00fcht auf war der Stadtsportbund Hagen am Sonntag Teil der Kids Avenue in der Hagener Innenstadt. Auf der Kinder-Erlebnis-Meile konnten zahlreiche Kinder das Kinderbewegungsabzeichen \u201eKibaz\u201c [&hellip;]<\/p>\n","protected":false},"author":15,"featured_media":9042,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[27],"tags":[],"class_list":["post-9040","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bewegung, Spiel und Spa\u00df bei der Kids Avenue - Stadtsportbund Hagen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ssb-hagen.de\/index.php\/2026\/05\/12\/bewegung-spiel-und-spass-bei-der-kids-avenue\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bewegung, Spiel und Spa\u00df bei der Kids Avenue - Stadtsportbund Hagen\" \/>\n<meta property=\"og:description\" content=\"Im Rahmen der Veranstaltung Hagen bl\u00fcht auf war der Stadtsportbund Hagen am Sonntag Teil der Kids Avenue in der Hagener Innenstadt. Auf der Kinder-Erlebnis-Meile konnten zahlreiche Kinder das Kinderbewegungsabzeichen \u201eKibaz\u201c [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ssb-hagen.de\/index.php\/2026\/05\/12\/bewegung-spiel-und-spass-bei-der-kids-avenue\/\" \/>\n<meta property=\"og:site_name\" content=\"Stadtsportbund Hagen\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100066611322930\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-12T13:39:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T13:39:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ssb-hagen.de\/wp-content\/uploads\/2026\/05\/IMG_20260510_131301-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Tim Fischer\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tim Fischer\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ssb-hagen.de\\\/index.php\\\/2026\\\/05\\\/12\\\/bewegung-spiel-und-spass-bei-der-kids-avenue\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ssb-hagen.de\\\/index.php\\\/2026\\\/05\\\/12\\\/bewegung-spiel-und-spass-bei-der-kids-avenue\\\/\"},\"author\":{\"name\":\"Tim Fischer\",\"@id\":\"https:\\\/\\\/ssb-hagen.de\\\/#\\\/schema\\\/person\\\/bb49e1617a18c581c7912bfeaf92ce0f\"},\"headline\":\"Bewegung, Spiel und Spa\u00df bei der Kids Avenue\",\"datePublished\":\"2026-05-12T13:39:47+00:00\",\"dateModified\":\"2026-05-12T13:39:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ssb-hagen.de\\\/index.php\\\/2026\\\/05\\\/12\\\/bewegung-spiel-und-spass-bei-der-kids-avenue\\\/\"},\"wordCount\":242,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/ssb-hagen.de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/ssb-hagen.de\\\/index.php\\\/2026\\\/05\\\/12\\\/bewegung-spiel-und-spass-bei-der-kids-avenue\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ssb-hagen.de\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_20260510_131301-scaled.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ssb-hagen.de\\\/index.php\\\/2026\\\/05\\\/12\\\/bewegung-spiel-und-spass-bei-der-kids-avenue\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ssb-hagen.de\\\/index.php\\\/2026\\\/05\\\/12\\\/bewegung-spiel-und-spass-bei-der-kids-avenue\\\/\",\"url\":\"https:\\\/\\\/ssb-hagen.de\\\/index.php\\\/2026\\\/05\\\/12\\\/bewegung-spiel-und-spass-bei-der-kids-avenue\\\/\",\"name\":\"Bewegung, Spiel und Spa\u00df bei der Kids Avenue - Stadtsportbund Hagen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ssb-hagen.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ssb-hagen.de\\\/index.php\\\/2026\\\/05\\\/12\\\/bewegung-spiel-und-spass-bei-der-kids-avenue\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ssb-hagen.de\\\/index.php\\\/2026\\\/05\\\/12\\\/bewegung-spiel-und-spass-bei-der-kids-avenue\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ssb-hagen.de\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_20260510_131301-scaled.jpg\",\"datePublished\":\"2026-05-12T13:39:47+00:00\",\"dateModified\":\"2026-05-12T13:39:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ssb-hagen.de\\\/index.php\\\/2026\\\/05\\\/12\\\/bewegung-spiel-und-spass-bei-der-kids-avenue\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ssb-hagen.de\\\/index.php\\\/2026\\\/05\\\/12\\\/bewegung-spiel-und-spass-bei-der-kids-avenue\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/ssb-hagen.de\\\/index.php\\\/2026\\\/05\\\/12\\\/bewegung-spiel-und-spass-bei-der-kids-avenue\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ssb-hagen.de\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_20260510_131301-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/ssb-hagen.de\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_20260510_131301-scaled.jpg\",\"width\":2560,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ssb-hagen.de\\\/index.php\\\/2026\\\/05\\\/12\\\/bewegung-spiel-und-spass-bei-der-kids-avenue\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/ssb-hagen.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bewegung, Spiel und Spa\u00df bei der Kids Avenue\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ssb-hagen.de\\\/#website\",\"url\":\"https:\\\/\\\/ssb-hagen.de\\\/\",\"name\":\"Stadtsportbund Hagen e.V.\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\\\/\\\/ssb-hagen.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ssb-hagen.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ssb-hagen.de\\\/#organization\",\"name\":\"Stadtsportbund Hagen e.V.\",\"url\":\"https:\\\/\\\/ssb-hagen.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/ssb-hagen.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ssb-hagen.de\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-favicon_ssb-Hagen.png\",\"contentUrl\":\"https:\\\/\\\/ssb-hagen.de\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-favicon_ssb-Hagen.png\",\"width\":512,\"height\":512,\"caption\":\"Stadtsportbund Hagen e.V.\"},\"image\":{\"@id\":\"https:\\\/\\\/ssb-hagen.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100066611322930\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ssb-hagen.de\\\/#\\\/schema\\\/person\\\/bb49e1617a18c581c7912bfeaf92ce0f\",\"name\":\"Tim Fischer\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3c90609fbf7bc87f44a2c4411663b8f2c3e7f07d81eb4dfd1dc1bcc3148262a9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3c90609fbf7bc87f44a2c4411663b8f2c3e7f07d81eb4dfd1dc1bcc3148262a9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3c90609fbf7bc87f44a2c4411663b8f2c3e7f07d81eb4dfd1dc1bcc3148262a9?s=96&d=mm&r=g\",\"caption\":\"Tim Fischer\"},\"url\":\"https:\\\/\\\/ssb-hagen.de\\\/index.php\\\/author\\\/tim-fischerssb-hagen-de\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bewegung, Spiel und Spa\u00df bei der Kids Avenue - Stadtsportbund Hagen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ssb-hagen.de\/index.php\/2026\/05\/12\/bewegung-spiel-und-spass-bei-der-kids-avenue\/","og_locale":"de_DE","og_type":"article","og_title":"Bewegung, Spiel und Spa\u00df bei der Kids Avenue - Stadtsportbund Hagen","og_description":"Im Rahmen der Veranstaltung Hagen bl\u00fcht auf war der Stadtsportbund Hagen am Sonntag Teil der Kids Avenue in der Hagener Innenstadt. Auf der Kinder-Erlebnis-Meile konnten zahlreiche Kinder das Kinderbewegungsabzeichen \u201eKibaz\u201c [&hellip;]","og_url":"https:\/\/ssb-hagen.de\/index.php\/2026\/05\/12\/bewegung-spiel-und-spass-bei-der-kids-avenue\/","og_site_name":"Stadtsportbund Hagen","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100066611322930","article_published_time":"2026-05-12T13:39:47+00:00","article_modified_time":"2026-05-12T13:39:52+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/ssb-hagen.de\/wp-content\/uploads\/2026\/05\/IMG_20260510_131301-scaled.jpg","type":"image\/jpeg"}],"author":"Tim Fischer","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Tim Fischer","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ssb-hagen.de\/index.php\/2026\/05\/12\/bewegung-spiel-und-spass-bei-der-kids-avenue\/#article","isPartOf":{"@id":"https:\/\/ssb-hagen.de\/index.php\/2026\/05\/12\/bewegung-spiel-und-spass-bei-der-kids-avenue\/"},"author":{"name":"Tim Fischer","@id":"https:\/\/ssb-hagen.de\/#\/schema\/person\/bb49e1617a18c581c7912bfeaf92ce0f"},"headline":"Bewegung, Spiel und Spa\u00df bei der Kids Avenue","datePublished":"2026-05-12T13:39:47+00:00","dateModified":"2026-05-12T13:39:52+00:00","mainEntityOfPage":{"@id":"https:\/\/ssb-hagen.de\/index.php\/2026\/05\/12\/bewegung-spiel-und-spass-bei-der-kids-avenue\/"},"wordCount":242,"commentCount":0,"publisher":{"@id":"https:\/\/ssb-hagen.de\/#organization"},"image":{"@id":"https:\/\/ssb-hagen.de\/index.php\/2026\/05\/12\/bewegung-spiel-und-spass-bei-der-kids-avenue\/#primaryimage"},"thumbnailUrl":"https:\/\/ssb-hagen.de\/wp-content\/uploads\/2026\/05\/IMG_20260510_131301-scaled.jpg","articleSection":["News"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ssb-hagen.de\/index.php\/2026\/05\/12\/bewegung-spiel-und-spass-bei-der-kids-avenue\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ssb-hagen.de\/index.php\/2026\/05\/12\/bewegung-spiel-und-spass-bei-der-kids-avenue\/","url":"https:\/\/ssb-hagen.de\/index.php\/2026\/05\/12\/bewegung-spiel-und-spass-bei-der-kids-avenue\/","name":"Bewegung, Spiel und Spa\u00df bei der Kids Avenue - Stadtsportbund Hagen","isPartOf":{"@id":"https:\/\/ssb-hagen.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ssb-hagen.de\/index.php\/2026\/05\/12\/bewegung-spiel-und-spass-bei-der-kids-avenue\/#primaryimage"},"image":{"@id":"https:\/\/ssb-hagen.de\/index.php\/2026\/05\/12\/bewegung-spiel-und-spass-bei-der-kids-avenue\/#primaryimage"},"thumbnailUrl":"https:\/\/ssb-hagen.de\/wp-content\/uploads\/2026\/05\/IMG_20260510_131301-scaled.jpg","datePublished":"2026-05-12T13:39:47+00:00","dateModified":"2026-05-12T13:39:52+00:00","breadcrumb":{"@id":"https:\/\/ssb-hagen.de\/index.php\/2026\/05\/12\/bewegung-spiel-und-spass-bei-der-kids-avenue\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ssb-hagen.de\/index.php\/2026\/05\/12\/bewegung-spiel-und-spass-bei-der-kids-avenue\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/ssb-hagen.de\/index.php\/2026\/05\/12\/bewegung-spiel-und-spass-bei-der-kids-avenue\/#primaryimage","url":"https:\/\/ssb-hagen.de\/wp-content\/uploads\/2026\/05\/IMG_20260510_131301-scaled.jpg","contentUrl":"https:\/\/ssb-hagen.de\/wp-content\/uploads\/2026\/05\/IMG_20260510_131301-scaled.jpg","width":2560,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/ssb-hagen.de\/index.php\/2026\/05\/12\/bewegung-spiel-und-spass-bei-der-kids-avenue\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/ssb-hagen.de\/"},{"@type":"ListItem","position":2,"name":"Bewegung, Spiel und Spa\u00df bei der Kids Avenue"}]},{"@type":"WebSite","@id":"https:\/\/ssb-hagen.de\/#website","url":"https:\/\/ssb-hagen.de\/","name":"Stadtsportbund Hagen e.V.","description":"Just another WordPress site","publisher":{"@id":"https:\/\/ssb-hagen.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ssb-hagen.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/ssb-hagen.de\/#organization","name":"Stadtsportbund Hagen e.V.","url":"https:\/\/ssb-hagen.de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/ssb-hagen.de\/#\/schema\/logo\/image\/","url":"https:\/\/ssb-hagen.de\/wp-content\/uploads\/2022\/07\/cropped-favicon_ssb-Hagen.png","contentUrl":"https:\/\/ssb-hagen.de\/wp-content\/uploads\/2022\/07\/cropped-favicon_ssb-Hagen.png","width":512,"height":512,"caption":"Stadtsportbund Hagen e.V."},"image":{"@id":"https:\/\/ssb-hagen.de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100066611322930"]},{"@type":"Person","@id":"https:\/\/ssb-hagen.de\/#\/schema\/person\/bb49e1617a18c581c7912bfeaf92ce0f","name":"Tim Fischer","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/3c90609fbf7bc87f44a2c4411663b8f2c3e7f07d81eb4dfd1dc1bcc3148262a9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3c90609fbf7bc87f44a2c4411663b8f2c3e7f07d81eb4dfd1dc1bcc3148262a9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3c90609fbf7bc87f44a2c4411663b8f2c3e7f07d81eb4dfd1dc1bcc3148262a9?s=96&d=mm&r=g","caption":"Tim Fischer"},"url":"https:\/\/ssb-hagen.de\/index.php\/author\/tim-fischerssb-hagen-de\/"}]}},"_links":{"self":[{"href":"https:\/\/ssb-hagen.de\/index.php\/wp-json\/wp\/v2\/posts\/9040","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ssb-hagen.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ssb-hagen.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ssb-hagen.de\/index.php\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/ssb-hagen.de\/index.php\/wp-json\/wp\/v2\/comments?post=9040"}],"version-history":[{"count":8,"href":"https:\/\/ssb-hagen.de\/index.php\/wp-json\/wp\/v2\/posts\/9040\/revisions"}],"predecessor-version":[{"id":9054,"href":"https:\/\/ssb-hagen.de\/index.php\/wp-json\/wp\/v2\/posts\/9040\/revisions\/9054"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ssb-hagen.de\/index.php\/wp-json\/wp\/v2\/media\/9042"}],"wp:attachment":[{"href":"https:\/\/ssb-hagen.de\/index.php\/wp-json\/wp\/v2\/media?parent=9040"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ssb-hagen.de\/index.php\/wp-json\/wp\/v2\/categories?post=9040"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ssb-hagen.de\/index.php\/wp-json\/wp\/v2\/tags?post=9040"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}